{"id":18492,"date":"2023-11-21T12:39:48","date_gmt":"2023-11-21T11:39:48","guid":{"rendered":"https:\/\/abamobile.com\/web\/?post_type=portfolio&#038;p=18492"},"modified":"2025-06-06T15:15:37","modified_gmt":"2025-06-06T13:15:37","slug":"app-lotofly-administracion-loterias-movil","status":"publish","type":"portfolio","link":"https:\/\/abamobile.com\/web\/portfolio\/app-lotofly-administracion-loterias-movil\/","title":{"rendered":"Desarrollo de una app de loter\u00eda Lotofly"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-o4kcjp8-da24e1b8bea45f9ce913749ea00ce62e\">\n.avia-section.av-o4kcjp8-da24e1b8bea45f9ce913749ea00ce62e{\nbackground-color:#fcfcfc;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-o4kcjp8-da24e1b8bea45f9ce913749ea00ce62e main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nrlc4sc-1821216dda4e0eb8e5def0d554c98516\">\n.flex_column.av-nrlc4sc-1821216dda4e0eb8e5def0d554c98516{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-nrlc4sc-1821216dda4e0eb8e5def0d554c98516 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ncosaf0-0a34b301e22154e75a7360164ee78640\">\n#top .hr.hr-invisible.av-ncosaf0-0a34b301e22154e75a7360164ee78640{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-ncosaf0-0a34b301e22154e75a7360164ee78640 hr-invisible  avia-builder-el-2  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mnoeg9o-cd74c11abac2a546ffae48ba09bcbf9a\">\n#top .av_textblock_section.av-mnoeg9o-cd74c11abac2a546ffae48ba09bcbf9a .avia_textblock{\nfont-size:14px;\n}\n<\/style>\n<section  class='av_textblock_section av-mnoeg9o-cd74c11abac2a546ffae48ba09bcbf9a'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong><span style=\"color: #333333;\">DESARROLLO DE APP<\/span><\/strong><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-li1qhyfa-f99faa1b15a306608abb5a40118bfa9f'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>Lotofly, desarrollo de una app de loter\u00eda<\/h1>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li1qpcrj-cf61c1b4a2bf676fe6ab50f66f8348ee\">\n#top .av_textblock_section.av-li1qpcrj-cf61c1b4a2bf676fe6ab50f66f8348ee .avia_textblock{\nfont-size:17px;\n}\n<\/style>\n<section  class='av_textblock_section av-li1qpcrj-cf61c1b4a2bf676fe6ab50f66f8348ee'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">En ABAMobile hemos trabajado en el desarrollo de una app de loter\u00eda que funciona como una <strong><span style=\"color: #333333;\">administraci\u00f3n de loter\u00edas digital para los usuarios<\/span><\/strong>.<\/span><\/p>\n<p>Lotofly es una <strong><span style=\"color: #333333;\">app h\u00edbrida e innovadora hecha con Ionic<\/span><\/strong><span style=\"font-weight: 400;\"> que permite a los usuarios participar en Loter\u00edas y Apuestas del Estado vincul\u00e1ndoles con un punto de venta de confianza y validando las apuestas.<\/span><\/p>\n<p><strong><span style=\"color: #333333;\">\u00a1Desc\u00e1rgala ya!<\/span><\/strong><\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-lldk767v-5f30483365947c9cb90b31353378141e avia-buttonrow-left  avia-builder-el-6  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lldk6h1h-dc316c207bb88ec86f34bf6033c32695\">\n#top #wrap_all .avia-button.av-lldk6h1h-dc316c207bb88ec86f34bf6033c32695{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=es.lotofly.app\" class=\"avia-button av-lldk6h1h-dc316c207bb88ec86f34bf6033c32695 avia-icon_select-yes-left-icon avia-size-large avia-color-theme-color\" target=\"_blank\" rel=\"noopener noreferrer\"><span class='avia_button_icon avia_button_icon_left ' aria-hidden='true' data-av_icon='\ue91c' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Descargar en Android<\/span><\/a>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lldk6y1g-64f0bb5e334eaa482560bd30c644c1f5\">\n#top #wrap_all .avia-button.av-lldk6y1g-64f0bb5e334eaa482560bd30c644c1f5{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href=\"https:\/\/apps.apple.com\/es\/app\/lotofly-loter%C3%ADa-online\/id6449784273\" class=\"avia-button av-lldk6y1g-64f0bb5e334eaa482560bd30c644c1f5 avia-icon_select-yes-left-icon avia-size-large avia-color-theme-color\" target=\"_blank\" rel=\"noopener noreferrer\"><span class='avia_button_icon avia_button_icon_left ' aria-hidden='true' data-av_icon='\ue920' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Descargar en iOS<\/span><\/a>\n<\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kvgv03g-69416f5b10c802aa586e3c7b3c1dbeef\">\n.flex_column.av-kvgv03g-69416f5b10c802aa586e3c7b3c1dbeef{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-kvgv03g-69416f5b10c802aa586e3c7b3c1dbeef av_one_half  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k9utqrg-341023e566e1dd99e370d926196bbf0d\">\n#top .hr.hr-invisible.av-k9utqrg-341023e566e1dd99e370d926196bbf0d{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k9utqrg-341023e566e1dd99e370d926196bbf0d hr-invisible  avia-builder-el-8  el_before_av_image  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7ee8lgc-c93bf85a66fa06e5ffc91f310c140cc7\">\n.avia-image-container.av-7ee8lgc-c93bf85a66fa06e5ffc91f310c140cc7 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-7ee8lgc-c93bf85a66fa06e5ffc91f310c140cc7 av-styling- avia-align-center  avia-builder-el-9  el_after_av_hr  avia-builder-el-last '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-19071 avia-img-lazy-loading-not-19071 avia_image' src=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/app-lotofly.png\" alt='app lotofly' title='app lotofly'  height=\"400\" width=\"600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/app-lotofly.png 600w, https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/app-lotofly-300x200.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/p><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-k3agnlo-437cd2a4201ea3a101f47afde2aa3b7b main_color avia-section-default avia-no-border-styling  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-j3eblek-322c12675b6f8421b79b58333135c955\">\n.flex_column.av-j3eblek-322c12675b6f8421b79b58333135c955{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-j3eblek-322c12675b6f8421b79b58333135c955 av_one_half  avia-builder-el-11  el_before_av_one_half  avia-builder-el-first  first flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ijqyhks-e6e75a0298028498d6f36ff929ed94f8\">\n#top .hr.hr-invisible.av-ijqyhks-e6e75a0298028498d6f36ff929ed94f8{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-ijqyhks-e6e75a0298028498d6f36ff929ed94f8 hr-invisible  avia-builder-el-12  el_before_av_textblock  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-i9e6zq4-9ed840e88c71fd9232d7b625f0ab36df'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Cliente<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-hob3bfg-9c2df34c53d8c8d4dd266aabf43c7d61\">\n#top .hr.av-hob3bfg-9c2df34c53d8c8d4dd266aabf43c7d61{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-hob3bfg-9c2df34c53d8c8d4dd266aabf43c7d61 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-hob3bfg-9c2df34c53d8c8d4dd266aabf43c7d61 hr-custom  avia-builder-el-14  el_after_av_textblock  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-hears4c-f8cfb096dd49650f33ebe367a9b1c343\">\n.flex_column.av-hears4c-f8cfb096dd49650f33ebe367a9b1c343{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-hears4c-f8cfb096dd49650f33ebe367a9b1c343 av_one_half  avia-builder-el-15  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gn28zy4-8b93163b6d54dc92dc79bd83a2de0a3b\">\n#top .hr.hr-invisible.av-gn28zy4-8b93163b6d54dc92dc79bd83a2de0a3b{\nmargin-top:-20px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-gn28zy4-8b93163b6d54dc92dc79bd83a2de0a3b hr-invisible  avia-builder-el-16  el_before_av_textblock  avia-builder-el-first  av-desktop-hide av-medium-hide av-small-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li1q29lw-228b134d33a43e0906b2c8f601346748\">\n#top .av_textblock_section.av-li1q29lw-228b134d33a43e0906b2c8f601346748 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-li1q29lw-228b134d33a43e0906b2c8f601346748'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.lotofly.es\/\" target=\"_blank\" rel=\"nofollow noopener\">Lotofly<\/a> es una empresa enfocada en la <strong><span style=\"color: #333333;\">venta de Loter\u00eda a trav\u00e9s de una aplicaci\u00f3n m\u00f3vil.<\/span><\/strong>\u00a0 C<\/span><span style=\"font-weight: 400;\">onsigue ser una plataforma a trav\u00e9s de la cual los usuarios participan en su punto de venta de confianza de Loter\u00edas y Apuestas del Estado.<\/span><\/p>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-left  avia-builder-el-18  el_after_av_textblock  avia-builder-el-last ' ><a href='#formulario-contacto'  class='avia-button av-fq4uyik-5cafe4b09ef2feb332923302ddcd085e avia-icon_select-no avia-size-large avia-position-left avia-color-theme-color' ><span class='avia_iconbox_title' >CONTACTA CON NOSOTROS<\/span><\/a><\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ff8kg0s-9ac89ae9128d1e9b1742196a9ae8b23b\">\n.avia-section.av-ff8kg0s-9ac89ae9128d1e9b1742196a9ae8b23b{\nbackground-color:#fcfcfc;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-ff8kg0s-9ac89ae9128d1e9b1742196a9ae8b23b main_color avia-section-default avia-no-border-styling  avia-builder-el-19  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ew0bqyk-7bcc2fc923f7c8dcf7e12c98d6a00fe4\">\n.flex_column.av-ew0bqyk-7bcc2fc923f7c8dcf7e12c98d6a00fe4{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-ew0bqyk-7bcc2fc923f7c8dcf7e12c98d6a00fe4 av_one_half  avia-builder-el-20  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-hide-on-mobile av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ecni0jg-85b129521b6054954c72f2f0dcbb1bf3\">\n#top .hr.hr-invisible.av-ecni0jg-85b129521b6054954c72f2f0dcbb1bf3{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-ecni0jg-85b129521b6054954c72f2f0dcbb1bf3 hr-invisible  avia-builder-el-21  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li1q2igt-580886a3847c668cb7a20de88b8eae42\">\n#top .av_textblock_section.av-li1q2igt-580886a3847c668cb7a20de88b8eae42 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-li1q2igt-580886a3847c668cb7a20de88b8eae42'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Con el objetivo de adaptarse cada vez mejor a los consumidores, Lotofly necesitaba el desarrollo de una app de loter\u00eda que permitiera a los clientes<\/span><strong><span style=\"color: #333333;\"> tener una administraci\u00f3n digital siempre disponible.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s del desarrollo de una app, Lotofly quer\u00eda conseguir la<\/span><span style=\"font-weight: 400;\"> digitalizaci\u00f3n de las Administraciones de Loter\u00edas y la fidelizaci\u00f3n de los usuarios. Para ello se ha querido poner<\/span><span style=\"font-weight: 400;\">\u00a0el foco en los m\u00f3viles, dispositivos que llevamos siempre con nosotros.<\/span><\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-dvmuz24-48c3ebe239c2488a0aba4b312b357c4f\">\n.flex_column.av-dvmuz24-48c3ebe239c2488a0aba4b312b357c4f{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-dvmuz24-48c3ebe239c2488a0aba4b312b357c4f av_one_half  avia-builder-el-23  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-dfkoxi4-89e43344ae3791096fba8e5f37745e1f\">\n#top .hr.hr-invisible.av-dfkoxi4-89e43344ae3791096fba8e5f37745e1f{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-dfkoxi4-89e43344ae3791096fba8e5f37745e1f hr-invisible  avia-builder-el-24  el_before_av_textblock  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-dab6nng-f31f7515047f82d5635dc5be511975b5'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Necesidad<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1al01wc-aedbcf563ef603c0743deaf124e63f9d\">\n#top .hr.av-1al01wc-aedbcf563ef603c0743deaf124e63f9d{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-1al01wc-aedbcf563ef603c0743deaf124e63f9d .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-1al01wc-aedbcf563ef603c0743deaf124e63f9d hr-custom  avia-builder-el-26  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li1q46bw-39daebac453597c3a17e8ee4761100d9\">\n#top .av_textblock_section.av-li1q46bw-39daebac453597c3a17e8ee4761100d9 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-li1q46bw-39daebac453597c3a17e8ee4761100d9'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-desktop-hide av-medium-hide av-small-hide avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Con el objetivo de adaptarse cada vez mejor a los consumidores, Lotofly necesitaba el desarrollo de una app de loter\u00eda que permitiera a los clientes<\/span><strong><span style=\"color: #333333;\"> tener una administraci\u00f3n digital siempre disponible.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s del desarrollo de una app, Lotofly quer\u00eda conseguir la<\/span><span style=\"font-weight: 400;\"> digitalizaci\u00f3n de las Administraciones de Loter\u00edas y la fidelizaci\u00f3n de los usuarios. Para ello se ha querido poner<\/span><span style=\"font-weight: 400;\">\u00a0el foco en los m\u00f3viles, dispositivos que llevamos siempre con nosotros.<\/span><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bzu6lrw-7a30e7513cd0b174573d9cfcc4dfdba9\">\n#top .hr.hr-invisible.av-bzu6lrw-7a30e7513cd0b174573d9cfcc4dfdba9{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-bzu6lrw-7a30e7513cd0b174573d9cfcc4dfdba9 hr-invisible  avia-builder-el-28  el_after_av_textblock  avia-builder-el-last  av-desktop-hide av-medium-hide av-small-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-bxhirjw-c0015f49fec0eeb04b0a6d9b74e62900 main_color avia-section-default avia-no-border-styling  avia-builder-el-29  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bcalwzg-e4d5bc02e3073d161f1ba7b17c719a04\">\n.flex_column.av-bcalwzg-e4d5bc02e3073d161f1ba7b17c719a04{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-bcalwzg-e4d5bc02e3073d161f1ba7b17c719a04 av_one_half  avia-builder-el-30  el_before_av_one_half  avia-builder-el-first  first flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b0kug1o-fcd6cd618f17526c1776e28472da74fb\">\n#top .hr.hr-invisible.av-b0kug1o-fcd6cd618f17526c1776e28472da74fb{\nheight:35px;\n}\n<\/style>\n<div  class='hr av-b0kug1o-fcd6cd618f17526c1776e28472da74fb hr-invisible  avia-builder-el-31  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-11x0wws-696cb8a566966453118a47dcaf35d7ec'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Soluci\u00f3n<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-u40bdo-0261287a9a19e41adc48b3e5fd190713\">\n#top .hr.av-u40bdo-0261287a9a19e41adc48b3e5fd190713{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-u40bdo-0261287a9a19e41adc48b3e5fd190713 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-u40bdo-0261287a9a19e41adc48b3e5fd190713 hr-custom  avia-builder-el-33  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li1q2r7i-6491edf1b6069ed5a82ee79aada79998\">\n#top .av_textblock_section.av-li1q2r7i-6491edf1b6069ed5a82ee79aada79998 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-li1q2r7i-6491edf1b6069ed5a82ee79aada79998'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Desde el equipo de ABAMobile comenzamos con el <\/span><strong><span style=\"color: #333333;\">desarrollo de una app de loter\u00eda disponible para iOS y Android.<\/span><\/strong><\/p>\n<p>Es una aplicaci\u00f3n h\u00edbrida hecha con Ionic a trav\u00e9s de la cual los usuarios pueden llevar a cabo<span style=\"font-weight: 400;\">\u00a0la compra de Loter\u00edas y Apuestas del Estado. <\/span><strong><span style=\"color: #333333;\">El objetivo de Lotofly es que la app funcione como una Administraci\u00f3n de Loter\u00edas siempre disponible para los usuarios.<\/span><\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gracias al sistema de registro, los puntos de venta podr\u00e1n integrarse en la aplicaci\u00f3n.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong><span style=\"color: #333333;\">Lotofly se puede vincular a un punto de venta de confianza a trav\u00e9s del uso de c\u00f3digos QR.<\/span><\/strong><span style=\"font-weight: 400;\"> De esta forma se sabe qui\u00e9n valida las apuestas y d\u00f3nde est\u00e1n los boletos y en caso de premio, saber a qui\u00e9n acudir.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong><span style=\"color: #333333;\">Los pagos son 100% seguros y est\u00e1n garantizados.<\/span><\/strong><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">No tiene comisiones y los usuarios solo pagan por el precio de las apuestas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Todo ello hace que Lotofly sea una aplicaci\u00f3n f\u00e1cil de utilizar con un registro r\u00e1pido y sencillo que permitir\u00e1 a los usuarios utilizarla <\/span><strong><span style=\"color: #333333;\">desde, d\u00f3nde y cu\u00e1ndo quieran.<\/span><\/strong><\/p>\n<div class=\"W4P4ne \">\n<div class=\"PHBdkd\" data-content-height=\"144\">\n<div class=\"DWPxHb\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-left  avia-builder-el-35  el_after_av_textblock  avia-builder-el-last ' ><a href='#formulario-contacto'  class='avia-button av-8y7dzh8-124a6b0a5b30b18d591b52dcc35c64ea avia-icon_select-no avia-size-large avia-position-left avia-color-theme-color' ><span class='avia_iconbox_title' >CONTACTA CON NOSOTROS<\/span><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8d6uh30-74d448e5c6120b080dba28ec9ffb5286\">\n.flex_column.av-8d6uh30-74d448e5c6120b080dba28ec9ffb5286{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-8d6uh30-74d448e5c6120b080dba28ec9ffb5286 av_one_half  avia-builder-el-36  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic fade-in av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-t0ppgc-024faef67ec5f31ce54ae2db0c23be22\">\n#top .hr.hr-invisible.av-t0ppgc-024faef67ec5f31ce54ae2db0c23be22{\nheight:70px;\n}\n<\/style>\n<div  class='hr av-t0ppgc-024faef67ec5f31ce54ae2db0c23be22 hr-invisible  avia-builder-el-37  el_before_av_image  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lldk20qo-66de75ef1d2da81f16bfe1dacc3b1554\">\n.avia-image-container.av-lldk20qo-66de75ef1d2da81f16bfe1dacc3b1554 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lldk20qo-66de75ef1d2da81f16bfe1dacc3b1554 av-styling- avia-align-center  avia-builder-el-38  el_after_av_hr  avia-builder-el-last '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-19072 avia-img-lazy-loading-not-19072 avia_image' src=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/desarrollo-aplicacion-movil-lotofly.png\" alt='Lotofly desarrollo de una app de loter\u00eda' title='Lotofly desarrollo de una app de loter\u00eda'  height=\"500\" width=\"600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/desarrollo-aplicacion-movil-lotofly.png 600w, https:\/\/abamobile.com\/web\/wp-content\/uploads\/2023\/08\/desarrollo-aplicacion-movil-lotofly-300x250.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6n64tek-608b833e031fe8837a218a74ce714269\">\n.avia-section.av-6n64tek-608b833e031fe8837a218a74ce714269{\nbackground-color:#fcfcfc;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-6n64tek-608b833e031fe8837a218a74ce714269 main_color avia-section-default avia-no-border-styling  avia-builder-el-39  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-68zawd8-caf71d37788a82ba5aea5f7ccb8a847c'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Otros de nuestros trabajos<\/h2>\n<\/div><\/section>\n<div id='av-masonry-1' class='av-masonry av-j8uixo-6f360f813f7a20a21721528399cd777a noHover av-fixed-size av-large-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-4 av-caption-always av-caption-style- av-masonry-entries av-orientation-square '><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/abamobile.com\/web\/portfolio\/app-movil-que-conecta-y-transforma-la-atencion-sanitaria\/\" id=\"av-masonry-1-item-26793\" data-av-masonry-item=\"26793\" class=\"av-masonry-entry isotope-item post-26793 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-salud-fitness  av-masonry-item-with-image\" title=\"app movil para el sector sanitario\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\"><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/10\/app-movil-para-el-sector-sanitario-705x494.webp);\"  title=\"app movil para el sector sanitario\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Una app m\u00f3vil que conecta y transforma la atenci\u00f3n sanitaria<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/solucion-movil-que-optimiza-y-gestiona-servicios-de-grupo-secon\/\" id=\"av-masonry-1-item-26786\" data-av-masonry-item=\"26786\" class=\"av-masonry-entry isotope-item post-26786 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-app  av-masonry-item-with-image\" title=\"desarrollo app para grupo secon\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\"><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/10\/desarrollo-app-para-grupo-secon-705x494.webp);\"  title=\"desarrollo app para grupo secon\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >De procesos obsoletos a la digitalizaci\u00f3n de Grupo Secon<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/desarrollo-de-app-para-mantenimiento-sistemas-gransolar\/\" id=\"av-masonry-1-item-26233\" data-av-masonry-item=\"26233\" class=\"av-masonry-entry isotope-item post-26233 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-energia  av-masonry-item-with-image\" title=\"app de mantenimiento para gransolar\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\"><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/05\/app-de-mantenimiento-para-gransolar-705x494.webp);\"  title=\"app de mantenimiento para gransolar\"   alt=\"app de mantenimiento para gransolar\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Desarrollo de la app de mantenimiento para Gransolar<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/aplicacion-para-optimizar-la-fuerza-de-ventas-en-ragt\/\" id=\"av-masonry-1-item-26211\" data-av-masonry-item=\"26211\" class=\"av-masonry-entry isotope-item post-26211 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-industria  av-masonry-item-with-image\" title=\"app para optimizar la fuerza de ventas\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\"><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/05\/app-para-optimizar-la-fuerza-de-ventas-705x494.webp);\"  title=\"app para optimizar la fuerza de ventas\"   alt=\"app para optimizar la fuerza de ventas\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Aplicaci\u00f3n para optimizar la fuerza de ventas en Ragt<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><a class='av-masonry-pagination av-masonry-load-more' href='#load-more'  data-ids=''  data-action=''  data-link='portfolio_entries'  data-post_type='post, page, attachment, revision, nav_menu_item, custom_css, customize_changeset, oembed_cache, user_request, wp_block, wp_template, wp_template_part, wp_global_styles, wp_navigation, wp_font_family, wp_font_face, mc4wp-form, wpforms, wpforms-template, portfolio, avia_framework_post, rm_content_editor'  data-items='4'  data-size='fixed'  data-image_size='masonry'  data-gap='large'  data-overlay_fx=''  data-animation='active'  data-offset='0'  data-container_links='active'  data-link_dest=''  data-lightbox_text=''  data-lazy_loading='disabled'  data-container_class='av-masonry-entries'  data-paginate='load_more'  data-caption_elements='title excerpt'  data-caption_display='always'  data-caption_styling=''  data-wc_prod_visible=''  data-wc_prod_hidden='hide'  data-wc_prod_featured=''  data-prod_order_by=''  data-prod_order=''  data-sort='no'  data-columns='4'  data-auto_ratio='1.7'  data-set_breadcrumb='1'  data-custom_markup=''  data-query_orderby='date'  data-query_order='DESC'  data-color=''  data-custom_bg=''  data-custom_class=''  data-orientation='av-orientation-square'  data-date_filter=''  data-date_filter_start=''  data-date_filter_end=''  data-date_filter_format='yy\/mm\/dd'  data-period_filter_unit_1='1'  data-period_filter_unit_2='year'  data-id=''  data-taxonomy='portfolio_entries'  data-categories='173,394,396,449,451,501,630,499,453,626,700,505,511,384,628,742,443,632,447,760,445,441,392,509,390,175,724,515,223,507,513,388,117,63,519,517'  data-avno='5831530f99'>Cargar m\u00e1s<\/a><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='formulario-contacto'  class='avia-section av-lp9tf48v-31fcd45879493e4351d3afdc555ea52d main_color avia-section-default avia-no-border-styling  avia-builder-el-42  el_after_av_section  el_before_av_codeblock  avia-bg-style-parallax container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6xxykv0-fa00ecd5e29b5ae4f00b85ee22bca0ac\">\n.flex_column.av-6xxykv0-fa00ecd5e29b5ae4f00b85ee22bca0ac{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-6xxykv0-fa00ecd5e29b5ae4f00b85ee22bca0ac av_one_fifth  avia-builder-el-43  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding '   ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6kc0z5o-f66ba9f289db1be7dfed6fc6970e8a7f\">\n.flex_column.av-6kc0z5o-f66ba9f289db1be7dfed6fc6970e8a7f{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-6kc0z5o-f66ba9f289db1be7dfed6fc6970e8a7f av_three_fifth  avia-builder-el-44  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding '   ><section  class='av_textblock_section av-66nh2e4-04ffdee676a0de645bad2d68f600910c'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><span style=\"color: #333333;\">\u00bfQuieres una app para tu empresa?<\/span><\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5vmcxwc-c341c07b533f42d3bb3f9932e088ec0a\">\n#top .av_textblock_section.av-5vmcxwc-c341c07b533f42d3bb3f9932e088ec0a .avia_textblock{\nfont-size:18px;\n}\n<\/style>\n<section  class='av_textblock_section av-5vmcxwc-c341c07b533f42d3bb3f9932e088ec0a'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\"><span style=\"color: #333333;\">\u00a1Ponte en contacto con nosotros y cu\u00e9ntanos la idea que tienes en mente!<\/span><\/p>\n<\/div><\/section><br \/>\n<\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-112py7w-4c6ae2fd8d41e8b7172bbc77bb4f3591\">\n.flex_column.av-112py7w-4c6ae2fd8d41e8b7172bbc77bb4f3591{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-112py7w-4c6ae2fd8d41e8b7172bbc77bb4f3591 av_one_fifth  avia-builder-el-48  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding '   ><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_6'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18492'><div class='entry-content-wrapper clearfix'>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":19073,"comment_status":"open","ping_status":"closed","template":"","tags":[],"portfolio_entries":[700],"class_list":["post-18492","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-apps-finanzas-y-servicios-bancarios"],"_links":{"self":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio\/18492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/comments?post=18492"}],"version-history":[{"count":0,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio\/18492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/media\/19073"}],"wp:attachment":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/media?parent=18492"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/tags?post=18492"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio_entries?post=18492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}