{"id":18448,"date":"2024-11-26T10:21:08","date_gmt":"2024-11-26T09:21:08","guid":{"rendered":"https:\/\/abamobile.com\/web\/?post_type=portfolio&#038;p=18448"},"modified":"2024-11-26T10:21:08","modified_gmt":"2024-11-26T09:21:08","slug":"desarrollo-mvp-para-alumbrado-profesional","status":"publish","type":"portfolio","link":"https:\/\/abamobile.com\/web\/portfolio\/desarrollo-mvp-para-alumbrado-profesional\/","title":{"rendered":"Desarrollo de un MVP para alumbrado profesional"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ibrou5s-b17b998c2886246077ea2698c865deaf\">\n.avia-section.av-ibrou5s-b17b998c2886246077ea2698c865deaf{\nbackground-color:#fcfcfc;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-ibrou5s-b17b998c2886246077ea2698c865deaf main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-hj1n6pc-57685f37525a29aba11a460a334f7d8f\">\n.flex_column.av-hj1n6pc-57685f37525a29aba11a460a334f7d8f{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-hj1n6pc-57685f37525a29aba11a460a334f7d8f av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-h7oqofk-75bd770e3a3878a3de3c1ee21b34cbd6\">\n#top .hr.hr-invisible.av-h7oqofk-75bd770e3a3878a3de3c1ee21b34cbd6{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-h7oqofk-75bd770e3a3878a3de3c1ee21b34cbd6 hr-invisible  avia-builder-el-2  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gxh1d80-c721117bee5a95c6327d1686553b6afc\">\n#top .av_textblock_section.av-gxh1d80-c721117bee5a95c6327d1686553b6afc .avia_textblock{\nfont-size:14px;\n}\n<\/style>\n<section  class='av_textblock_section av-gxh1d80-c721117bee5a95c6327d1686553b6afc'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong><span style=\"color: #333333;\">DESARROLLO DE APP<\/span><\/strong><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-gi02csw-52e569420c0b4c4932b55fde93037abc'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>Desarrollo de un MVP para alumbrado profesional<\/h1>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-f8jogmo-34ceb2868df44ff18e6fd77f76b396d8\">\n#top .av_textblock_section.av-f8jogmo-34ceb2868df44ff18e6fd77f76b396d8 .avia_textblock{\nfont-size:17px;\n}\n<\/style>\n<section  class='av_textblock_section av-f8jogmo-34ceb2868df44ff18e6fd77f76b396d8'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Este MVP es una<strong><span style=\"color: #333333;\">\u00a0aplicaci\u00f3n m\u00f3vil que permite visualizar diferentes par\u00e1metros e informaci\u00f3n de un edificio.<\/span><\/strong> Todo ello gracias a luminarias inteligentes.<\/span><\/p>\n<p>\u00a1Se crean as\u00ed espacios y lugares de trabajo m\u00e1s inteligentes y eficientes!<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-left  avia-builder-el-6  el_after_av_textblock  avia-builder-el-last ' ><a href='#formulario-contacto'  class='avia-button av-li053pam-e177fe9629d9f7331a663932f3737fab avia-icon_select-no avia-size-large avia-position-left avia-color-theme-color' ><span class='avia_iconbox_title' >CONT\u00c1CTANOS AHORA<\/span><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-d4zw2y8-260bb4f33f470c2d9b278b9cbe3f02c1\">\n.flex_column.av-d4zw2y8-260bb4f33f470c2d9b278b9cbe3f02c1{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-d4zw2y8-260bb4f33f470c2d9b278b9cbe3f02c1 av_one_half  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic fade-in av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ciqkrv4-f50f1532f57929a18c02f16ddd2c60ad\">\n#top .hr.hr-invisible.av-ciqkrv4-f50f1532f57929a18c02f16ddd2c60ad{\nheight:15px;\n}\n<\/style>\n<div  class='hr av-ciqkrv4-f50f1532f57929a18c02f16ddd2c60ad hr-invisible  avia-builder-el-8  el_before_av_image  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-c8qyyhc-02a92ab17a3cc06151a06366fdf99818\">\n.avia-image-container.av-c8qyyhc-02a92ab17a3cc06151a06366fdf99818 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-c8qyyhc-02a92ab17a3cc06151a06366fdf99818 av-styling- avia-align-center  avia-builder-el-9  el_after_av_hr  avia-builder-el-last '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-25101 avia-img-lazy-loading-not-25101 avia_image' src=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-mvp.webp\" alt='desarrollo mvp' title='desarrollo mvp'  height=\"400\" width=\"600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-mvp.webp 600w, https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-mvp-300x200.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/p><\/div><\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-15z6tw0-1eb4f1e35cc1c8c265c5b288b752d22d main_color avia-section-default avia-no-border-styling  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b3vfzps-512fa03bfcbd48faf078e50f57290ea0\">\n.flex_column.av-b3vfzps-512fa03bfcbd48faf078e50f57290ea0{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-b3vfzps-512fa03bfcbd48faf078e50f57290ea0 av_one_half  avia-builder-el-11  el_before_av_one_half  avia-builder-el-first  first flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-awi58k0-47440d842ec5717efd2a3469f9ffdd1c\">\n#top .hr.hr-invisible.av-awi58k0-47440d842ec5717efd2a3469f9ffdd1c{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-awi58k0-47440d842ec5717efd2a3469f9ffdd1c hr-invisible  avia-builder-el-12  el_before_av_textblock  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-lhyvme0y-1cb993dfb81eeb3dd605165f898c1027'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Cliente<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ac7fxtc-a053d3650407b0aabdf76b5dbf74d9a8\">\n#top .hr.av-ac7fxtc-a053d3650407b0aabdf76b5dbf74d9a8{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-ac7fxtc-a053d3650407b0aabdf76b5dbf74d9a8 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-ac7fxtc-a053d3650407b0aabdf76b5dbf74d9a8 hr-custom  avia-builder-el-14  el_after_av_textblock  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9pwa6r4-91226b73f378782ff0f51a780c85034e\">\n.flex_column.av-9pwa6r4-91226b73f378782ff0f51a780c85034e{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-9pwa6r4-91226b73f378782ff0f51a780c85034e av_one_half  avia-builder-el-15  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9l4mx1s-133a92d3f5f8f374450ce77e8ca2a3d9\">\n#top .hr.hr-invisible.av-9l4mx1s-133a92d3f5f8f374450ce77e8ca2a3d9{\nmargin-top:-20px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-9l4mx1s-133a92d3f5f8f374450ce77e8ca2a3d9 hr-invisible  avia-builder-el-16  el_before_av_textblock  avia-builder-el-first  av-desktop-hide av-medium-hide av-small-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lhyvng99-058b6de459db19e0c212cf97310daf6a\">\n#top .av_textblock_section.av-lhyvng99-058b6de459db19e0c212cf97310daf6a .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-lhyvng99-058b6de459db19e0c212cf97310daf6a'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Nuestro cliente es <strong><span style=\"color: #333333;\">l\u00edder en iluminaci\u00f3n convencional, LED e iluminaci\u00f3n conectada<\/span><\/strong> para profesionales y consumidores. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ofrece una cartera de paquetes de software basados en IoT que <strong><span style=\"color: #333333;\">gestiona, supervisa y controla los sistemas de iluminaci\u00f3n<\/span><\/strong> que incluyen luminarias conectadas, sensores y otros dispositivos.<\/span><\/p>\n<\/div><\/section><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-8siiq6o-2836258f980409388003bebd02c650f1 main_color avia-section-default avia-no-border-styling  avia-builder-el-18  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8izabxs-8a5474747d2356fb4adbc413cfc0d5d1\">\n.flex_column.av-8izabxs-8a5474747d2356fb4adbc413cfc0d5d1{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-8izabxs-8a5474747d2356fb4adbc413cfc0d5d1 av_one_half  avia-builder-el-19  el_before_av_one_half  avia-builder-el-first  first flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7vexs28-6dae3038be902f9b7bea2e42152ae391\">\n#top .hr.hr-invisible.av-7vexs28-6dae3038be902f9b7bea2e42152ae391{\nmargin-top:-20px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-7vexs28-6dae3038be902f9b7bea2e42152ae391 hr-invisible  avia-builder-el-20  el_before_av_textblock  avia-builder-el-first  av-desktop-hide av-medium-hide av-small-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-nk035c-d21bdb3893e5b460b95bec5874380bd2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-desktop-hide avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Necesidad<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-64qahv4-b603658bd43c577b178b9090f912cc20\">\n#top .hr.av-64qahv4-b603658bd43c577b178b9090f912cc20{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-64qahv4-b603658bd43c577b178b9090f912cc20 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-64qahv4-b603658bd43c577b178b9090f912cc20 hr-custom  avia-builder-el-22  el_after_av_textblock  el_before_av_textblock  av-desktop-hide av-medium-hide hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2z0z3lc-1465ec2a3ff8226f6b2058fa7fd9956b\">\n#top .av_textblock_section.av-2z0z3lc-1465ec2a3ff8226f6b2058fa7fd9956b .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-2z0z3lc-1465ec2a3ff8226f6b2058fa7fd9956b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">Conscientes de la <strong><span style=\"color: #333333;\">importancia de la conectividad y los datos para las empresas<\/span><\/strong>, nuestro cliente ofrece servicios donde los productos de iluminaci\u00f3n y el Internet de las Cosas tienen un papel fundamental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Necesitaba una soluci\u00f3n que se integrara con sus herramientas y poder <strong><span style=\"color: #333333;\">visualizar de forma unificada la informaci\u00f3n y los datos de un edifici<\/span><span style=\"color: #333333;\">o<\/span><\/strong> como por ejemplo, el consumo energ\u00e9tico.<\/span><\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-qxinps-a83f7b2a94a9f4c48c06df5ad5d0ec92\">\n.flex_column.av-qxinps-a83f7b2a94a9f4c48c06df5ad5d0ec92{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-qxinps-a83f7b2a94a9f4c48c06df5ad5d0ec92 av_one_half  avia-builder-el-24  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-78nabjk-ff36cd4ab2a2f25593fb1da1361e9485\">\n#top .hr.hr-invisible.av-78nabjk-ff36cd4ab2a2f25593fb1da1361e9485{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-78nabjk-ff36cd4ab2a2f25593fb1da1361e9485 hr-invisible  avia-builder-el-25  el_before_av_textblock  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-m1izum1l-b9447c2da1a8574fd220addfe4d671c6'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-small-hide av-mini-hide avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Necesidad<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m1izuft2-923c87455985f7408f889324f5c8f9b0\">\n#top .hr.av-m1izuft2-923c87455985f7408f889324f5c8f9b0{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-m1izuft2-923c87455985f7408f889324f5c8f9b0 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-m1izuft2-923c87455985f7408f889324f5c8f9b0 hr-custom  avia-builder-el-27  el_after_av_textblock  avia-builder-el-last  av-small-hide av-mini-hide hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-5q35auo-0e051c4725de33257f7bbebda1dea918 main_color avia-section-default avia-no-border-styling  avia-builder-el-28  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-55mfiwg-2bb29737f22294d33e7fcd795bd11bc2\">\n.flex_column.av-55mfiwg-2bb29737f22294d33e7fcd795bd11bc2{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-55mfiwg-2bb29737f22294d33e7fcd795bd11bc2 av_one_half  avia-builder-el-29  el_before_av_one_half  avia-builder-el-first  first flex_column_div  av-animated-generic left-to-right av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4tdwweo-164da0d3872a9765a85b5dcccdbe756f\">\n#top .hr.hr-invisible.av-4tdwweo-164da0d3872a9765a85b5dcccdbe756f{\nheight:35px;\n}\n<\/style>\n<div  class='hr av-4tdwweo-164da0d3872a9765a85b5dcccdbe756f hr-invisible  avia-builder-el-30  el_before_av_textblock  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-4b6pd68-435d8148f44e5b40c8a28f83431790c8'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Soluci\u00f3n<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3ztzads-b2580b7d11ff520c748dddb345fb1012\">\n#top .hr.av-3ztzads-b2580b7d11ff520c748dddb345fb1012{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-3ztzads-b2580b7d11ff520c748dddb345fb1012 .hr-inner{\nwidth:70px;\nborder-color:#595959;\n}\n<\/style>\n<div  class='hr av-3ztzads-b2580b7d11ff520c748dddb345fb1012 hr-custom  avia-builder-el-32  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lhyvqkla-6ad3de014c43fe1edcbd04c384c4010e\">\n#top .av_textblock_section.av-lhyvqkla-6ad3de014c43fe1edcbd04c384c4010e .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-lhyvqkla-6ad3de014c43fe1edcbd04c384c4010e'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><span style=\"font-weight: 400;\">En el equipo de ABAMobile hemos trabajado en el <a href=\"https:\/\/abamobile.com\/web\/mvp-creamos-producto-minimo-viable-tecnologia-movil-empresas-startups\/\">desarrollo de un Producto M\u00ednimo Viable (MVP)<\/a> que se integra con la plataforma empresarial de nuestro cliente. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este MVP es una <strong><span style=\"color: #333333;\">aplicaci\u00f3n que permite visualizar diferentes par\u00e1metros e informaci\u00f3n de un edificio<\/span><\/strong> gracias a las luminarias inteligentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con esta soluci\u00f3n m\u00f3vil se crean edificios inteligentes que permiten<strong><span style=\"color: #333333;\"> visualizar informaci\u00f3n energ\u00e9tica y de ocupaci\u00f3n, optimizar espacios, observar datos en tiempo real<\/span><\/strong>, as\u00ed como tendencias y patrones de consumo energ\u00e9tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gracias a este MVP se puede <strong><span style=\"color: #333333;\">optimizar la utilizaci\u00f3n de un espacio<\/span><\/strong>, as\u00ed como observar informaci\u00f3n acerca de la iluminaci\u00f3n, la temperatura, la humedad o la calidad del aire, entre otros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se consigue crear espacios optimizados gracias al an\u00e1lisis de datos.<\/span><\/p>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-left  avia-builder-el-34  el_after_av_textblock  avia-builder-el-last ' ><a href='#formulario-contacto'  class='avia-button av-2am55jk-057845078ef2599d5248c9c000590e83 avia-icon_select-no avia-size-large avia-position-left avia-color-theme-color' ><span class='avia_iconbox_title' >CONTACTA CON NOSOTROS<\/span><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3kpmnzk-6e5259c24be6f5dd39de177e011b8eb8\">\n.flex_column.av-3kpmnzk-6e5259c24be6f5dd39de177e011b8eb8{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-3kpmnzk-6e5259c24be6f5dd39de177e011b8eb8 av_one_half  avia-builder-el-35  el_after_av_one_half  avia-builder-el-last  flex_column_div  av-animated-generic fade-in av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2wbzl5c-6be573d4894530dbd571eb5a96229c10\">\n#top .hr.hr-invisible.av-2wbzl5c-6be573d4894530dbd571eb5a96229c10{\nheight:65px;\n}\n<\/style>\n<div  class='hr av-2wbzl5c-6be573d4894530dbd571eb5a96229c10 hr-invisible  avia-builder-el-36  el_before_av_image  avia-builder-el-first  av-mini-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2os77hs-15aee72b07700c401018d95d34eff7b4\">\n.avia-image-container.av-2os77hs-15aee72b07700c401018d95d34eff7b4 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-2os77hs-15aee72b07700c401018d95d34eff7b4 av-styling- avia-align-center  avia-builder-el-37  el_after_av_hr  avia-builder-el-last '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-25102 avia-img-lazy-loading-not-25102 avia_image' src=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-producto-minimo-viable.webp\" alt='desarrollo producto minimo viable' title='desarrollo producto minimo viable'  height=\"500\" width=\"600\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-producto-minimo-viable.webp 600w, https:\/\/abamobile.com\/web\/wp-content\/uploads\/2024\/11\/desarrollo-producto-minimo-viable-300x250.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-23bpa34-c6d93e65b417311130b5e10156d4ffcc\">\n.avia-section.av-23bpa34-c6d93e65b417311130b5e10156d4ffcc{\nbackground-color:#fcfcfc;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-23bpa34-c6d93e65b417311130b5e10156d4ffcc main_color avia-section-default avia-no-border-styling  avia-builder-el-38  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-1pw9avk-ff53c94bbbb06bbbf524502948c5292c'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\">Otros de nuestros trabajos<\/h2>\n<\/div><\/section>\n<div id='av-masonry-1' class='av-masonry av-mzn29c-99c0fa1e66d3dfb9d24ed6f7ffc2f38c noHover av-fixed-size av-large-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-4 av-caption-always av-caption-style- av-masonry-entries av-orientation-square '><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/abamobile.com\/web\/portfolio\/app-movil-que-conecta-y-transforma-la-atencion-sanitaria\/\"  id='av-masonry-1-item-26793' data-av-masonry-item='26793' class='av-masonry-entry isotope-item post-26793 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-salud-fitness  av-masonry-item-with-image' title=\"app movil para el sector sanitario\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/10\/app-movil-para-el-sector-sanitario-705x494.webp);\"  title=\"app movil para el sector sanitario\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Una app m\u00f3vil que conecta y transforma la atenci\u00f3n sanitaria<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/solucion-movil-que-optimiza-y-gestiona-servicios-de-grupo-secon\/\"  id='av-masonry-1-item-26786' data-av-masonry-item='26786' class='av-masonry-entry isotope-item post-26786 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-app  av-masonry-item-with-image' title=\"desarrollo app para grupo secon\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/10\/desarrollo-app-para-grupo-secon-705x494.webp);\"  title=\"desarrollo app para grupo secon\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >De procesos obsoletos a la digitalizaci\u00f3n de Grupo Secon<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/desarrollo-de-app-para-mantenimiento-sistemas-gransolar\/\"  id='av-masonry-1-item-26233' data-av-masonry-item='26233' class='av-masonry-entry isotope-item post-26233 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-energia  av-masonry-item-with-image' title=\"app de mantenimiento para gransolar\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/05\/app-de-mantenimiento-para-gransolar-705x494.webp);\"  title=\"app de mantenimiento para gransolar\"   alt=\"app de mantenimiento para gransolar\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Desarrollo de la app de mantenimiento para Gransolar<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/abamobile.com\/web\/portfolio\/aplicacion-para-optimizar-la-fuerza-de-ventas-en-ragt\/\"  id='av-masonry-1-item-26211' data-av-masonry-item='26211' class='av-masonry-entry isotope-item post-26211 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-apps-industria  av-masonry-item-with-image' title=\"app para optimizar la fuerza de ventas\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/abamobile.com\/web\/wp-content\/uploads\/2025\/05\/app-para-optimizar-la-fuerza-de-ventas-705x494.webp);\"  title=\"app para optimizar la fuerza de ventas\"   alt=\"app para optimizar la fuerza de ventas\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Aplicaci\u00f3n para optimizar la fuerza de ventas en Ragt<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><a class='av-masonry-pagination av-masonry-load-more' href='#load-more'  data-ids=''  data-action=''  data-link='portfolio_entries, 173,394,449,451,501,630,499,453,626,628,632,447,445,441,225,223,63'  data-post_type='post, page, attachment, revision, nav_menu_item, custom_css, customize_changeset, oembed_cache, user_request, wp_block, wp_template, wp_template_part, wp_global_styles, wp_navigation, wp_font_family, wp_font_face, mc4wp-form, wpforms, wpforms-template, portfolio, avia_framework_post, rm_content_editor'  data-items='4'  data-size='fixed'  data-image_size='masonry'  data-gap='large'  data-overlay_fx=''  data-animation='active'  data-offset='0'  data-container_links='active'  data-link_dest=''  data-lightbox_text=''  data-lazy_loading='disabled'  data-container_class='av-masonry-entries'  data-paginate='load_more'  data-caption_elements='title excerpt'  data-caption_display='always'  data-caption_styling=''  data-wc_prod_visible=''  data-wc_prod_hidden='hide'  data-wc_prod_featured=''  data-prod_order_by=''  data-prod_order=''  data-sort='no'  data-columns='4'  data-auto_ratio='1.7'  data-set_breadcrumb='1'  data-custom_markup=''  data-query_orderby='date'  data-query_order='DESC'  data-color=''  data-custom_bg=''  data-custom_class=''  data-orientation='av-orientation-square'  data-date_filter=''  data-date_filter_start=''  data-date_filter_end=''  data-date_filter_format='yy\/mm\/dd'  data-period_filter_unit_1='1'  data-period_filter_unit_2='year'  data-id=''  data-taxonomy='portfolio_entries'  data-categories='173,394,449,451,501,630,499,453,626,628,632,447,445,441,223,63'  data-avno='5831530f99'>Cargar m\u00e1s<\/a><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='formulario-contacto'  class='avia-section av-li05a4gm-36c27db6cdec37e5163c49489ab65823 main_color avia-section-default avia-no-border-styling  avia-builder-el-41  el_after_av_section  el_before_av_codeblock  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-1t5b4eo-a56beb1a80841abab3be522a818ab511 av_one_fifth  avia-builder-el-42  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div '   ><\/div><div class='flex_column av-4nhmpc-32be21210240a3d23de66a389fd07758 av_three_fifth  avia-builder-el-43  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div '   ><section  class='av_textblock_section av-li05bsku-dd18258dfaddd513476e84bd6925ead8'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><span style=\"color: #333333;\">\u00bfQuieres una app para tu empresa?<\/span><\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-li05cp6b-51052a2d3c336ce454726270b894ce7d\">\n#top .av_textblock_section.av-li05cp6b-51052a2d3c336ce454726270b894ce7d .avia_textblock{\nfont-size:20px;\n}\n<\/style>\n<section  class='av_textblock_section av-li05cp6b-51052a2d3c336ce454726270b894ce7d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\"><span style=\"color: #333333;\">\u00a1Ponte en contacto con nosotros y cu\u00e9ntanos la idea que tienes en mente!<\/span><\/p>\n<\/div><\/section><br \/>\n<\/p><\/div><div class='flex_column av-to41hs-8e5e5d4db7267ac9da1a5d3aa62399e4 av_one_fifth  avia-builder-el-47  el_after_av_three_fifth  avia-builder-el-last  flex_column_div '   ><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_6'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18448'><div class='entry-content-wrapper clearfix'>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":25103,"comment_status":"open","ping_status":"closed","template":"","tags":[],"portfolio_entries":[449],"class_list":["post-18448","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-app-alumbrado-profesional"],"_links":{"self":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio\/18448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/comments?post=18448"}],"version-history":[{"count":0,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio\/18448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/media\/25103"}],"wp:attachment":[{"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/media?parent=18448"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/tags?post=18448"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/abamobile.com\/web\/wp-json\/wp\/v2\/portfolio_entries?post=18448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}